{"id":1127,"count":1,"description":"","link":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/","name":"Emperor","slug":"emperor","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Emperor Archives ~ Mind&#039;s Eye TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emperor Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/\" \/>\n<meta property=\"og:site_name\" content=\"Mind&#039;s Eye TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/tag\\\/emperor\\\/\",\"url\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/tag\\\/emperor\\\/\",\"name\":\"Emperor Archives ~ Mind&#039;s Eye TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/tag\\\/emperor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/tag\\\/emperor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emperor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/#website\",\"url\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/\",\"name\":\"Mind&#039;s Eye TV\",\"description\":\"Open Up Your Eyes\",\"publisher\":{\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/#organization\",\"name\":\"Viceroy TV\",\"url\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ramonaleone.com\\\/tv\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/1633678203.318633-6935CD18-0838-4E51-AAED-D57D2541A0AC.png\",\"contentUrl\":\"https:\\\/\\\/ramonaleone.com\\\/tv\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/1633678203.318633-6935CD18-0838-4E51-AAED-D57D2541A0AC.png\",\"width\":750,\"height\":564,\"caption\":\"Viceroy TV\"},\"image\":{\"@id\":\"https:\\\/\\\/mindseyemag.com\\\/tv\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Emperor Archives ~ Mind&#039;s Eye TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/","og_locale":"en_US","og_type":"article","og_title":"Emperor Archives","og_url":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/","og_site_name":"Mind&#039;s Eye TV","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/","url":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/","name":"Emperor Archives ~ Mind&#039;s Eye TV","isPartOf":{"@id":"https:\/\/mindseyemag.com\/tv\/#website"},"breadcrumb":{"@id":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mindseyemag.com\/tv\/tag\/emperor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mindseyemag.com\/tv\/"},{"@type":"ListItem","position":2,"name":"Emperor"}]},{"@type":"WebSite","@id":"https:\/\/mindseyemag.com\/tv\/#website","url":"https:\/\/mindseyemag.com\/tv\/","name":"Mind&#039;s Eye TV","description":"Open Up Your Eyes","publisher":{"@id":"https:\/\/mindseyemag.com\/tv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mindseyemag.com\/tv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mindseyemag.com\/tv\/#organization","name":"Viceroy TV","url":"https:\/\/mindseyemag.com\/tv\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mindseyemag.com\/tv\/#\/schema\/logo\/image\/","url":"https:\/\/ramonaleone.com\/tv\/wp-content\/uploads\/2022\/03\/1633678203.318633-6935CD18-0838-4E51-AAED-D57D2541A0AC.png","contentUrl":"https:\/\/ramonaleone.com\/tv\/wp-content\/uploads\/2022\/03\/1633678203.318633-6935CD18-0838-4E51-AAED-D57D2541A0AC.png","width":750,"height":564,"caption":"Viceroy TV"},"image":{"@id":"https:\/\/mindseyemag.com\/tv\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mindseyemag.com\/tv\/wp-json\/wp\/v2\/tags\/1127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mindseyemag.com\/tv\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mindseyemag.com\/tv\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mindseyemag.com\/tv\/wp-json\/wp\/v2\/posts?tags=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}